{"id":5551,"date":"2025-03-21T17:35:53","date_gmt":"2025-03-21T17:35:53","guid":{"rendered":"https:\/\/prosistav.pt\/versao2\/?page_id=5551"},"modified":"2025-09-18T17:18:17","modified_gmt":"2025-09-18T17:18:17","slug":"paineis-digitais-interativos-2","status":"publish","type":"page","link":"https:\/\/prosistav.pt\/versao2\/produtos\/paineis-digitais-interativos-2\/","title":{"rendered":"Pain\u00e9is Digitais Interativos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5551\" class=\"elementor elementor-5551\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5609a8ae e-con-full e-flex e-con e-parent\" data-id=\"5609a8ae\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50abe96 elementor-widget elementor-widget-menu-anchor\" data-id=\"50abe96\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"TOP\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41e1b051 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"41e1b051\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comunica\u00e7\u00e3o din\u00e2mica e envolvente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29ad5fc2 animated-slow elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"29ad5fc2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7341925a animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7341925a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">pain\u00e9is digitais<BR>\ninterativos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3230273e elementor-invisible elementor-widget elementor-widget-image\" data-id=\"3230273e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/03\/paineis-digitais-interativos-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-5246\" alt=\"Pain\u00e9is Digitais Interativos\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/03\/paineis-digitais-interativos-150x150.png 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/03\/paineis-digitais-interativos.png 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-545974f5 e-flex e-con-boxed e-con e-parent\" data-id=\"545974f5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca77a15 elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ca77a15\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-family: Din, sans-serif; font-size: 24px; white-space-collapse: preserve;\">Os <strong>pain\u00e9is digitais interativos<\/strong> s\u00e3o ideais para apresenta\u00e7\u00e3o de informa\u00e7\u00f5es de forma din\u00e2mica, comunica\u00e7\u00e3o publicit\u00e1ria ou gest\u00e3o de conte\u00fados em ambientes industriais e comerciais.<\/span><\/p><p><span style=\"font-family: Din, sans-serif; font-size: 24px; white-space-collapse: preserve;\">Tecnologia moderna para captar aten\u00e7\u00e3o e otimizar a comunica\u00e7\u00e3o<\/span><span style=\"font-family: Din, sans-serif; font-size: 24px; white-space-collapse: preserve;\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-301d242c elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"301d242c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f7ed0b e-flex e-con-boxed e-con e-child\" data-id=\"2f7ed0b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4729dc5 e-con-full e-flex e-con e-child\" data-id=\"4729dc5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13464ef elementor-widget elementor-widget-image\" data-id=\"13464ef\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#quadros\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1500\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital-.jpg\" class=\"attachment-full size-full wp-image-9460\" alt=\"quadro interativo digital\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital-.jpg 1500w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital--300x300.jpg 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital--1024x1024.jpg 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital--150x150.jpg 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital--768x768.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc04b33 elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"cc04b33\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#quadros\">Quadros<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95fc6c9 e-con-full e-flex e-con e-child\" data-id=\"95fc6c9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ac294a elementor-widget elementor-widget-image\" data-id=\"0ac294a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#quiosques\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1500\" height=\"1500\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo.jpg\" class=\"attachment-full size-full wp-image-9484\" alt=\"kiosk - quisque digital interativo\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo.jpg 1500w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo-300x300.jpg 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo-1024x1024.jpg 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo-150x150.jpg 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo-768x768.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53ec979 elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"53ec979\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#quiosques\">Quiosques<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8feb15a e-con-full e-flex e-con e-child\" data-id=\"8feb15a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1be9518 elementor-widget elementor-widget-image\" data-id=\"1be9518\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#paineis\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao-1024x1024.png\" class=\"attachment-large size-large wp-image-9524\" alt=\"interior painel digital de ch\u00e3o\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao-1024x1024.png 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao-300x300.png 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao-150x150.png 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao-768x768.png 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee472af elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"ee472af\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#paineis\">Pain\u00e9is<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d933adf e-con-full e-flex e-con e-child\" data-id=\"d933adf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-191b021 elementor-widget elementor-widget-image\" data-id=\"191b021\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#montras\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1-1024x1024.png\" class=\"attachment-large size-large wp-image-9539\" alt=\"montra digital para exibi\u00e7\u00e3o de produtos em retalho e espa\u00e7os comerciais\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1-1024x1024.png 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1-300x300.png 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1-150x150.png 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1-768x768.png 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-258aa3c elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"258aa3c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#montras\">Montras<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52ae7ad e-con-full e-flex e-con e-child\" data-id=\"52ae7ad\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7be9946 elementor-widget elementor-widget-image\" data-id=\"7be9946\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#menus\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1-1024x1024.png\" class=\"attachment-large size-large wp-image-9544\" alt=\"Pain\u00e9is digitais para menus em restaura\u00e7\u00e3o\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1-1024x1024.png 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1-300x300.png 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1-150x150.png 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1-768x768.png 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-459444d elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"459444d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#montras\">Menus<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53da7090 e-flex e-con-boxed e-con e-parent\" data-id=\"53da7090\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4c1131a6 e-con-full e-flex e-con e-child\" data-id=\"4c1131a6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ca96b15 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5ca96b15\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DIGITAL SIGNAGE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71872f6 animated-slow elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"71872f6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-394fb6a3 animated-slow elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"394fb6a3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">COMUNICA\u00c7\u00c3O\nVISUAL<BR>\nDIN\u00c2MICA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-200f8ab animated-slow elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"200f8ab\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e51a991 elementor-widget elementor-widget-text-editor\" data-id=\"2e51a991\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4>O conte\u00fado visual animado atrai mais aten\u00e7\u00e3o do que os suportes est\u00e1ticos, estimulando a intera\u00e7\u00e3o com o p\u00fablico.<\/h4><h4>Estudos t\u00eam vindo a demonstrar que consumidores s\u00e3o mais propensos a manter na mem\u00f3ria as mensagens exibidas em telas digitais.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c6540c3 elementor-widget elementor-widget-image\" data-id=\"7c6540c3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3840\" height=\"2160\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/03\/paineis-.png\" class=\"attachment-full size-full wp-image-5555\" alt=\"paineis digitais interativos\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/03\/paineis-.png 3840w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/03\/paineis--300x169.png 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/03\/paineis--1024x576.png 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/03\/paineis--768x432.png 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/03\/paineis--1536x864.png 1536w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/03\/paineis--2048x1152.png 2048w\" sizes=\"(max-width: 3840px) 100vw, 3840px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc43101 elementor-widget__width-initial elementor-fixed elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"dc43101\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;fixed&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#TOP\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d3c6f1c e-flex e-con-boxed e-con e-parent\" data-id=\"1d3c6f1c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de43074 elementor-widget elementor-widget-menu-anchor\" data-id=\"de43074\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"quadros\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26bbb5d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"26bbb5d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fbd2f95 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7fbd2f95\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">quadros interativos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67c7fe22 elementor-widget elementor-widget-text-editor\" data-id=\"67c7fe22\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\">Solu\u00e7\u00f5es que combinam interatividade com as funcionalidades de quadro branco digital. Ideais para salas de aula ou escrit\u00f3rios, otimizando apresenta\u00e7\u00f5es e reuni\u00f5es.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-91ae14a e-flex e-con-boxed e-con e-parent\" data-id=\"91ae14a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1d14168 e-con-full e-flex e-con e-child\" data-id=\"1d14168\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a33702 elementor-widget elementor-widget-image\" data-id=\"9a33702\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital-1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9461\" alt=\"quadro interativo digital\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital-1-1024x1024.jpg 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital-1-300x300.jpg 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital-1-150x150.jpg 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital-1-768x768.jpg 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quadro-interativo-digital-1.jpg 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51e171a elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"51e171a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">quadro interativo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaaba62 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"eaaba62\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bd1b89 elementor-widget elementor-widget-text-editor\" data-id=\"3bd1b89\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Desenvolvidos para potenciar a colabora\u00e7\u00e3o em salas de aula, reuni\u00f5es e confer\u00eancias.<\/p><p>Combinam tecnologia de alta defini\u00e7\u00e3o com uma utiliza\u00e7\u00e3o intuitiva, permitindo transformar qualquer espa\u00e7o numa experi\u00eancia din\u00e2mica e envolvente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-183b1c0 e-con-full e-flex e-con e-child\" data-id=\"183b1c0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-132d166 elementor-widget elementor-widget-image\" data-id=\"132d166\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9485\" alt=\"quiosque de autoatendimento\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento-1024x1024.jpg 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento-300x300.jpg 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento-150x150.jpg 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento-768x768.jpg 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento.jpg 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ab968e elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7ab968e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">quadro nano<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04bbb6d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"04bbb6d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-613d423 elementor-widget elementor-widget-text-editor\" data-id=\"613d423\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Combina a familiaridade de um quadro negro com a interatividade digital, com uma integra\u00e7\u00e3o perfeita entre o ecr\u00e3 digital e os dois quadros tradicionais.<\/p><p>Os sub-quadros de escrita est\u00e3o interligados ao ecr\u00e3 principal, garantindo a sincroniza\u00e7\u00e3o em tempo real.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ff9c1d e-flex e-con-boxed e-con e-parent\" data-id=\"1ff9c1d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-882dc25 elementor-widget elementor-widget-menu-anchor\" data-id=\"882dc25\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"quiosques\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59517fa animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"59517fa\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quiosques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c41059e elementor-widget elementor-widget-text-editor\" data-id=\"c41059e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\">Os <strong data-start=\"84\" data-end=\"109\">Quiosques Interativos<\/strong> s\u00e3o solu\u00e7\u00f5es vers\u00e1teis que combinam tecnologia e usabilidade para diferentes contextos.\u00a0Podem ser utilizados para <strong data-start=\"237\" data-end=\"306\">mapas digitais, exibi\u00e7\u00e3o de publicidade, apresenta\u00e7\u00f5es multim\u00e9dia<\/strong> ou at\u00e9 como <strong data-start=\"319\" data-end=\"372\">quiosques de autoatendimento e compra de produtos.<\/strong>\u00a0Adaptam-se a diversos setores, oferecendo uma experi\u00eancia moderna, intuitiva e envolvente para os utilizadores.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d08cb86 e-flex e-con-boxed e-con e-parent\" data-id=\"d08cb86\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-df421fc e-con-full e-flex e-con e-child\" data-id=\"df421fc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481c4f6 elementor-widget elementor-widget-image\" data-id=\"481c4f6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9484\" alt=\"kiosk - quisque digital interativo\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo-1024x1024.jpg 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo-300x300.jpg 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo-150x150.jpg 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo-768x768.jpg 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/kiosk-quisoque-digital-interativo.jpg 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b67c87 elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9b67c87\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kiosk <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca6b5e9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ca6b5e9\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d25e66f elementor-widget elementor-widget-text-editor\" data-id=\"d25e66f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ecr\u00e3s interativos que combinam com funcionalidades de publicidade digital, para navega\u00e7\u00e3o em mapas, consultas de hor\u00e1rios e informa\u00e7\u00f5es em centros comerciais, esta\u00e7\u00f5es de transporte ou mesmo em empresas.\u200b<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d00eed e-con-full e-flex e-con e-child\" data-id=\"5d00eed\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8434886 elementor-widget elementor-widget-image\" data-id=\"8434886\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9485\" alt=\"quiosque de autoatendimento\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento-1024x1024.jpg 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento-300x300.jpg 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento-150x150.jpg 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento-768x768.jpg 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/quisoque-de-autoatendimento.jpg 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f996d4 elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7f996d4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">autoatendimento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aaa734 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5aaa734\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bdfae1 elementor-widget elementor-widget-text-editor\" data-id=\"2bdfae1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Permitem realizar pedidos, personalizar op\u00e7\u00f5es e efetuar pagamentos de forma simples e r\u00e1pida. Seja em restaura\u00e7\u00e3o, retalho, hotelaria ou transportes, estes quiosques s\u00e3o a escolha ideal para otimizar processos e valorizar o seu neg\u00f3cio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37d4f56 e-flex e-con-boxed e-con e-parent\" data-id=\"37d4f56\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-476727c elementor-widget elementor-widget-menu-anchor\" data-id=\"476727c\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"paineis\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f631e99 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f631e99\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pain\u00e9is publicit\u00e1rios interativos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1a4466 elementor-widget elementor-widget-text-editor\" data-id=\"f1a4466\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\">Os pain\u00e9is interativos digitais oferecem solu\u00e7\u00f5es modernas e vers\u00e1teis para comunica\u00e7\u00e3o visual em diferentes contextos. Dispon\u00edveis em diversos formatos \u2014 como floor standing, dual screen floor standing, indoor wall mounting e outros modelos \u2014 permitem transmitir conte\u00fados de forma din\u00e2mica, atrativa e eficaz.\u00a0<\/h4><h4 style=\"text-align: center;\">Ideais para espa\u00e7os comerciais, corporativos ou p\u00fablicos, estes equipamentos combinam design inovador com tecnologia de alto desempenho, garantindo m\u00e1xima visibilidade e impacto na comunica\u00e7\u00e3o.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f83fcc e-con-full e-flex e-con e-child\" data-id=\"9f83fcc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e9e2576 e-con-full e-flex e-con e-child\" data-id=\"e9e2576\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46c65c6 elementor-widget elementor-widget-image\" data-id=\"46c65c6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao-1024x1024.png\" class=\"attachment-large size-large wp-image-9524\" alt=\"interior painel digital de ch\u00e3o\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao-1024x1024.png 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao-300x300.png 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao-150x150.png 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao-768x768.png 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-chao.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7606ef elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d7606ef\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Painel de ch\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbdd94d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fbdd94d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2de131 elementor-widget elementor-widget-text-editor\" data-id=\"a2de131\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Com um design moderno e de f\u00e1cil integra\u00e7\u00e3o em qualquer ambiente, permitem a exibi\u00e7\u00e3o de conte\u00fados multim\u00e9dia de forma impactante, seja em lojas, centros comerciais, rece\u00e7\u00f5es ou eventos corporativos.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f9220a e-con-full e-flex e-con e-child\" data-id=\"0f9220a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1be509 elementor-widget elementor-widget-image\" data-id=\"e1be509\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-parede-1024x1024.png\" class=\"attachment-large size-large wp-image-9525\" alt=\"interior painel digital de parede\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-parede-1024x1024.png 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-parede-300x300.png 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-parede-150x150.png 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-parede-768x768.png 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/interior-painel-digital-de-parede.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f58b5e elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1f58b5e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Painel de parede<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef0dc82 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ef0dc82\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff9d681 elementor-widget elementor-widget-text-editor\" data-id=\"ff9d681\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Permitem transmitir conte\u00fados de forma cont\u00ednua e clara, sendo perfeitos para salas de espera, corredores, audit\u00f3rios ou \u00e1reas de atendimento, onde a informa\u00e7\u00e3o deve ser vis\u00edvel sem ocupar espa\u00e7o \u00fatil no ch\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7db946 e-flex e-con-boxed e-con e-parent\" data-id=\"f7db946\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db57e58 elementor-widget elementor-widget-menu-anchor\" data-id=\"db57e58\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"montras\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5c41a7 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f5c41a7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Montras<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8a7b39 elementor-widget elementor-widget-text-editor\" data-id=\"c8a7b39\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\">As montras digitais s\u00e3o uma solu\u00e7\u00e3o inovadora para atrair a aten\u00e7\u00e3o e destacar produtos em ambientes comerciais. Dispon\u00edveis em diferentes formatos \u2014 de um s\u00f3 lado, frente e verso ou em caixas LCD transparentes tipo box \u2014 permitem combinar exposi\u00e7\u00e3o f\u00edsica e comunica\u00e7\u00e3o digital num \u00fanico equipamento. Estas solu\u00e7\u00f5es s\u00e3o ideais para lojas de retalho, showrooms e espa\u00e7os de exposi\u00e7\u00e3o, onde \u00e9 essencial captar o olhar do cliente e transmitir mensagens de forma moderna e envolvente. Com elevada qualidade de imagem e design adapt\u00e1vel, as montras digitais tornam a experi\u00eancia de compra mais atrativa e interativa.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13cba93 e-con-full e-flex e-con e-child\" data-id=\"13cba93\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d4a97a8 e-con-full e-flex e-con e-child\" data-id=\"d4a97a8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09ebe8c elementor-widget elementor-widget-image\" data-id=\"09ebe8c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1-1024x1024.png\" class=\"attachment-large size-large wp-image-9539\" alt=\"montra digital para exibi\u00e7\u00e3o de produtos em retalho e espa\u00e7os comerciais\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1-1024x1024.png 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1-300x300.png 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1-150x150.png 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1-768x768.png 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/montras-digitais-1.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cef2de2 elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cef2de2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Montra Digital<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b920a9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8b920a9\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e092c14 elementor-widget elementor-widget-text-editor\" data-id=\"e092c14\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>As <strong>montras digitais<\/strong> s\u00e3o ideais para destacar produtos e campanhas em espa\u00e7os comerciais, criando impacto visual tanto no interior como no exterior da loja. <strong>Podem ser configuradas com ecr\u00e3s de um lado ou de dois lados<\/strong>, assegurando visibilidade em ambos os sentidos de circula\u00e7\u00e3o. Al\u00e9m disso, podem ser instaladas de forma fixa ao ch\u00e3o ou suspensas no teto, adaptando-se \u00e0s necessidades de cada espa\u00e7o. S\u00e3o a solu\u00e7\u00e3o perfeita para vitrinas modernas que combinam design elegante com comunica\u00e7\u00e3o digital de alta qualidade.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b59144 e-con-full e-flex e-con e-child\" data-id=\"4b59144\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf5b802 elementor-widget elementor-widget-image\" data-id=\"bf5b802\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/caixa-montra-digital-com-LCD-1024x1024.png\" class=\"attachment-large size-large wp-image-9540\" alt=\"\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/caixa-montra-digital-com-LCD-1024x1024.png 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/caixa-montra-digital-com-LCD-300x300.png 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/caixa-montra-digital-com-LCD-150x150.png 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/caixa-montra-digital-com-LCD-768x768.png 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/caixa-montra-digital-com-LCD.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cf6a57 elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4cf6a57\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caixa de exibi\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0ade48 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b0ade48\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12794dd elementor-widget elementor-widget-text-editor\" data-id=\"12794dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>As <strong>caixas de exibi\u00e7\u00e3o com painel LCD transparente<\/strong> oferecem uma forma inovadora de apresentar produtos, combinando a exposi\u00e7\u00e3o f\u00edsica com conte\u00fados digitais din\u00e2micos. Este tipo de solu\u00e7\u00e3o<strong> permite que o cliente veja o artigo real no interior da caixa enquanto informa\u00e7\u00f5es<\/strong>, imagens ou v\u00eddeos s\u00e3o projetados no ecr\u00e3 transparente. \u00c9 uma ferramenta diferenciadora para montras, showrooms e eventos, tornando a apresenta\u00e7\u00e3o mais envolvente e interativa, ao mesmo tempo que valoriza o produto exposto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36b8870 e-flex e-con-boxed e-con e-parent\" data-id=\"36b8870\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd34a8 elementor-widget elementor-widget-menu-anchor\" data-id=\"3fd34a8\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"menus\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef8dc5a animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ef8dc5a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Menus<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4265d13 elementor-widget elementor-widget-text-editor\" data-id=\"4265d13\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\">As solu\u00e7\u00f5es digitais para o setor da restaura\u00e7\u00e3o permitem modernizar a comunica\u00e7\u00e3o com os clientes, tornando-a mais atrativa e eficiente. Os pain\u00e9is de menu fixos \u00e0 parede s\u00e3o ideais para exibir menus din\u00e2micos, promo\u00e7\u00f5es e campanhas visuais em restaurantes, caf\u00e9s ou fast-food, garantindo atualiza\u00e7\u00e3o imediata de conte\u00fados e maior impacto junto dos clientes. Para complementar, existem tamb\u00e9m displays digitais de mesa ou de balc\u00e3o, perfeitos para destacar ofertas do dia, sugest\u00f5es personalizadas ou campanhas promocionais diretamente no ponto de decis\u00e3o de compra. Estas solu\u00e7\u00f5es oferecem versatilidade, eleg\u00e2ncia e efici\u00eancia, ajudando a criar uma experi\u00eancia de cliente mais envolvente e moderna.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a6d537 e-con-full e-flex e-con e-child\" data-id=\"6a6d537\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-bf05728 e-con-full e-flex e-con e-child\" data-id=\"bf05728\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a837caf elementor-widget elementor-widget-image\" data-id=\"a837caf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1-1024x1024.png\" class=\"attachment-large size-large wp-image-9544\" alt=\"Pain\u00e9is digitais para menus em restaura\u00e7\u00e3o\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1-1024x1024.png 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1-300x300.png 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1-150x150.png 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1-768x768.png 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/paineis-menu-digitais-para-restauracao-1.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a532616 elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a532616\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pain\u00e9is menu<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c34b52 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3c34b52\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f57184b elementor-widget elementor-widget-text-editor\" data-id=\"f57184b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Os pain\u00e9is digitais de parede s\u00e3o a solu\u00e7\u00e3o ideal para<strong> apresentar menus, promo\u00e7\u00f5es e conte\u00fados visuais de forma din\u00e2mica e apelativa em restaurantes<\/strong>, caf\u00e9s e espa\u00e7os de fast-food. Permitem atualizar a informa\u00e7\u00e3o em tempo real, facilitam a comunica\u00e7\u00e3o de campanhas e oferecem um design moderno que valoriza o ambiente do espa\u00e7o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95de24b e-con-full e-flex e-con e-child\" data-id=\"95de24b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cb7207 elementor-widget elementor-widget-image\" data-id=\"5cb7207\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/menu-digitais-para-mesas-e-balcao-1024x1024.png\" class=\"attachment-large size-large wp-image-9545\" alt=\"Menus digitais para colocar em mesas e balc\u00e3o em espa\u00e7os de restaura\u00e7\u00e3o\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/menu-digitais-para-mesas-e-balcao-1024x1024.png 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/menu-digitais-para-mesas-e-balcao-300x300.png 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/menu-digitais-para-mesas-e-balcao-150x150.png 150w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/menu-digitais-para-mesas-e-balcao-768x768.png 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2025\/09\/menu-digitais-para-mesas-e-balcao.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7607dd7 elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7607dd7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Menus digitais<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30d10e3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"30d10e3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aca141d elementor-widget elementor-widget-text-editor\" data-id=\"aca141d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Os <strong>displays digitais de mesa ou balc\u00e3o<\/strong> s\u00e3o perfeitos para <strong>destacar ofertas do dia, menus especiais ou campanhas promocionais<\/strong> diretamente no ponto de decis\u00e3o de compra. Compactos e elegantes, ajudam a captar a aten\u00e7\u00e3o dos clientes enquanto aguardam o servi\u00e7o, tornando a experi\u00eancia mais envolvente e aumentando as oportunidades de venda.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-880ef3a e-flex e-con-boxed e-con e-parent\" data-id=\"880ef3a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbf5178 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dbf5178\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pretende mais informa\u00e7\u00f5es sobre estas solu\u00e7\u00f5es?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae56de7 elementor-widget elementor-widget-text-editor\" data-id=\"ae56de7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Entre em contacto com os nossos especialistas!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e800c6e elementor-button-align-center elementor-widget elementor-widget-form\" data-id=\"e800c6e\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Seguinte&quot;,&quot;step_previous_label&quot;:&quot;Anterior&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Inscri\u00e7\u00e3o em forma\u00e7\u00e3o\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"5551\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"e800c6e\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"PROSISTAV\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_e5f0e83 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_e5f0e83\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_e5f0e83]\" id=\"form-field-field_e5f0e83\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefone\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMensagem\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mensagem\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Comunica\u00e7\u00e3o din\u00e2mica e envolvente pain\u00e9is digitais interativos Os pain\u00e9is digitais interativos s\u00e3o ideais para apresenta\u00e7\u00e3o de informa\u00e7\u00f5es de forma din\u00e2mica, comunica\u00e7\u00e3o publicit\u00e1ria ou gest\u00e3o de conte\u00fados em ambientes industriais e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":766,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-5551","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/pages\/5551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/comments?post=5551"}],"version-history":[{"count":109,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/pages\/5551\/revisions"}],"predecessor-version":[{"id":9861,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/pages\/5551\/revisions\/9861"}],"up":[{"embeddable":true,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/pages\/766"}],"wp:attachment":[{"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/media?parent=5551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}