{"id":3101,"date":"2019-09-13T07:58:29","date_gmt":"2019-09-13T07:58:29","guid":{"rendered":"https:\/\/prosistav.pt\/versao2\/?p=3101"},"modified":"2019-09-13T07:58:29","modified_gmt":"2019-09-13T07:58:29","slug":"sanyo-denki-nova-serie-de-servomotores-dc","status":"publish","type":"post","link":"https:\/\/prosistav.pt\/versao2\/sanyo-denki-nova-serie-de-servomotores-dc\/","title":{"rendered":"Sanyo Denki: nova s\u00e9rie de Servomotores DC"},"content":{"rendered":"<p><strong>Servomotores DC<em> SANMOTION K<\/em><br \/>\n<\/strong><strong>Economia de energia e varia\u00e7\u00e3o de velocidade reduzida<\/strong><\/p>\n<p>A <strong>SANYO DENKI\u00a0<\/strong>\u00a0desenvolveu e lan\u00e7ou os servomotores\u00a0DC <em>SANMOTION K<\/em> que permitem economizar energia e reduzir a varia\u00e7\u00e3o de velocidade. Estes motores s\u00e3o adequados para equipamentos de medi\u00e7\u00e3o de precis\u00e3o e equipamentos m\u00e9dicos.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-3102 aligncenter\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2019\/09\/20190529_sanmotion_k_PT.jpg\" alt=\"\" width=\"540\" height=\"250\" \/><\/p>\n<p><strong>Sequ\u00eancia<br \/>\n<\/strong>&#8211; Modelos de flange quadrada de 42 mm (sa\u00edda nominal: 23,40, 60W)<br \/>\n&#8211; Modelos de flange quadrada de 54 mm (sa\u00edda nominal: 60, 80, 110W)<br \/>\n&#8211; Modelos de flange quadrada de 76 mm (sa\u00edda nominal: 200, 300W)<br \/>\n&#8211; Modelos de flange quadrada de 88 mm (sa\u00edda nominal: 400, 500W)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Caracter\u00edsticas<br \/>\n<\/strong><strong>Precis\u00e3o melhorada:\u00a0<\/strong>O torque de engrenagem foi reduzido em at\u00e1 aproximadamente 50%, comparativamente com os servo motores DC atuais (<em>SANMOTION T<\/em>). Permitindo um funcionamento suave do motor, inclusivamente em velocidade baixa, melhorando assim a precis\u00e3o do movimento do equipamento.<br \/>\n<strong>Economia de energia:\u00a0<\/strong>A perda de energia foi reduzida em at\u00e9 aproximadamente 30%, comparativamente com os servo motores DC atuais (<em>SANMOTION T<\/em>). Reduzindo assim a gera\u00e7\u00e3o de calor emitida dentro do equipamento, contribuindo para economia de energia.<br \/>\n<strong>Modelos de baixa tens\u00e3o dispon\u00edveis:\u00a0<\/strong>Os motores de 42 e 54mm s\u00e3o fornecidos em duas gamas de tens\u00e3o: 24 e 75VDC. Os modelos de baixa tens\u00e3o s\u00e3o seguros para utiliza\u00e7\u00e3o em equipamentos m\u00e9dicos e outras aplica\u00e7\u00f5es em contacto pr\u00f3ximo com pessoas.<br \/>\n<strong>Compatibilidade de instala\u00e7\u00e3o:\u00a0<\/strong>Os novos motores t\u00eam compatibilidade de instala\u00e7\u00e3o com os motores DC atuais (<em>SANMOTION T<\/em>). Estes motores podem ser substitu\u00eddos sem alterar a instala\u00e7\u00e3o do equipamento.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Especifica\u00e7\u00f5es<\/strong><img decoding=\"async\" class=\"alignnone size-full wp-image-3103\" src=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2019\/09\/specifications.jpg\" alt=\"\" width=\"1196\" height=\"494\" srcset=\"https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2019\/09\/specifications.jpg 1196w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2019\/09\/specifications-300x124.jpg 300w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2019\/09\/specifications-768x317.jpg 768w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2019\/09\/specifications-1024x423.jpg 1024w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2019\/09\/specifications-830x343.jpg 830w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2019\/09\/specifications-230x95.jpg 230w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2019\/09\/specifications-350x145.jpg 350w, https:\/\/prosistav.pt\/versao2\/wp-content\/uploads\/2019\/09\/specifications-480x198.jpg 480w\" sizes=\"(max-width: 1196px) 100vw, 1196px\" \/><\/p>\n<p><strong>Aplica\u00e7\u00f5es<br \/>\n<\/strong>Equipamentos de medi\u00e7\u00e3o de elevada precis\u00e3o, equipamentos m\u00e9dicos, entre outros.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sanyodenki.com\/archive\/document\/product\/servo\/catalog_E_pdf\/SANMOTION_K_E.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Cat\u00e1logo<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Servomotores DC SANMOTION K Economia de energia e varia\u00e7\u00e3o de velocidade reduzida A SANYO DENKI\u00a0\u00a0desenvolveu e lan\u00e7ou os servomotores\u00a0DC SANMOTION K que permitem economizar energia e reduzir a varia\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/posts\/3101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/comments?post=3101"}],"version-history":[{"count":1,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/posts\/3101\/revisions"}],"predecessor-version":[{"id":3104,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/posts\/3101\/revisions\/3104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/media\/3102"}],"wp:attachment":[{"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/media?parent=3101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/categories?post=3101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prosistav.pt\/versao2\/wp-json\/wp\/v2\/tags?post=3101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}